{"id":2810,"date":"2017-05-24T11:09:18","date_gmt":"2017-05-24T11:09:18","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/factory-direct-sales-construction-hoist-sc200200-sc100100-success.html"},"modified":"2017-05-24T11:09:18","modified_gmt":"2017-05-24T11:09:18","slug":"factory-direct-sales-construction-hoist-sc200200-sc100100-success","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/factory-direct-sales-construction-hoist-sc200200-sc100100-success.html","title":{"rendered":"Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale484.jpg\" alt=\"Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)\" \/><br \/>\nImage of Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: elevador de materiais de constru\u00e7\u00e3o para venda<\/li>\n<li>N\u00famero do modelo: elevador de materiais de constru\u00e7\u00e3o para venda<\/li>\n<li>Mecanismo de eleva\u00e7\u00e3o: corrente de eleva\u00e7\u00e3o<\/li>\n<li>Acionamento\/Atua\u00e7\u00e3o do Elevador: Motor El\u00e9trico<\/li>\n<li>Poder: elevador<\/li>\n<li>Capacidade de carga nominal: elevador de materiais de constru\u00e7\u00e3o para venda<\/li>\n<li>Altura m\u00ednima de eleva\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m<\/li>\n<li>Tamanho da mesa: Motor el\u00e9trico<\/li>\n<li>Dimens\u00f5es totais: 2,8-3,2 m 1 pe\u00e7a\/5 mastros<\/li>\n<li>Weight:electric construction elevator<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tower Crane Type:electric construction elevator<\/li>\n<li>SC200\/200::building construction materials lift for sale<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Gaiola: Gaiola dupla (com opera\u00e7\u00e3o<\/li>\n<li>Sistema El\u00e9trico Principal: Schneider<\/li>\n<li>Instala\u00e7\u00e3o:Montado<\/li>\n<li>Comprimento ajust\u00e1vel da amarra\u00e7\u00e3o de parede e quantidade: 2,8-3,2 m 1 pe\u00e7a\/5 mastros<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2 m, 3*1,3*2,2 m<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pT1BJazRFSDRvRzg\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale402.jpg\" alt=\"Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale249.jpg\" alt=\"Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale238.jpg\" alt=\"Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success)\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale182.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Hoist Guiding Roller, Construction Elevator Roller<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: roller<\/li>\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>De: Sucesso<\/li>\n<li>Origem: Xangai<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Pacote de transporte: a caixa de madeira<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: M1.5 Stainlss Steel Gear Racks And Pinion in Bahrain, M1 M2 M3 M4 M5 M6 Cnc Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Faridabad, Maceio etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale108.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">lifting height 250m Double-cage construction hoist sc200\/200<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC150\/150, SCA200\/200<\/li>\n<li>Capacidade de carga nominal (kg): 1000kg-2000kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Dimens\u00e3o (C*L*A): 3,0*1,3(1,5)*2,2<\/li>\n<li>Peso do carregador: 2000 kg<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tipo: Equipamento de eleva\u00e7\u00e3o de constru\u00e7\u00e3o SC200\/200<\/li>\n<li>Tens\u00e3o-frequ\u00eancia: 380-50 Hz (pode ser ajustada conforme a necessidade do cliente)<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min, 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Capacidade nominal: 1000Kg \u2013 2000Kg<\/li>\n<li>Pot\u00eancia do motor: 11 kW * 2, 11 kW * 3, 15 kW * 2, 12 kW * 2, 13 kW * 2<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9000, CE, GOST, Padr\u00e3o Coreano<\/li>\n<li>Se\u00e7\u00e3o do mastro: 650*650*1508(mm) peso: 145Kg<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento de cozimento, Galvaniza\u00e7\u00e3o, Pintura<\/li>\n<li>Garantia: 1 ano<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1.5 Stainlss Steel Gear Racks And Pinion in Faridabad, Cnc Rack Gear in Maceio<\/div>\n<div class=\"alpha-text1\">Export to: Paraguay, Vadodara etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale159.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">supplier lift elevator\/wholesale mini lift 2500\/pa400b electric wire rope hoist elevator motor price<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC100, SC120, SC150, SC200 (cabine dupla ou cabine simples)<\/li>\n<li>Capacidade de carga nominal (kg): 2*2000kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min (tipo comum)<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m (tipo comum)<\/li>\n<li>Dimens\u00e3o (C*L*A):3m*1,3m(ou1,5m)*2,4m<\/li>\n<li>Peso do carregador: 2T\/gaiola<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Certificado de qualidade: ISO9000:2008, CE<\/li>\n<li>Tipo de acionamento: cremalheira e engrenagem<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*11kw, 2*15kw, 2*13kw<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento em forno, Zincagem a quente<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>keyword: lift elevator<\/li>\n<li>keyword2:wholesale mini lift 2500<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Small Pinion Gears in Paraguay, Baoda Hoist Gear Rack in Vadodara<\/div>\n<div class=\"alpha-text1\">Export to: Indore, Amsterdam, Mali, Bahrain etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale325.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">good price of rack and pinion<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:Modules1~modules 10, Stainless steel spur gear with rack, CNC Gear Rack,Tooth RACK gear<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o, A\u00e7o C45, G60.S45, S43<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: N\u00e3o padr\u00e3o<\/li>\n<li>Grau: padr\u00e3o<\/li>\n<li>cor:preto<\/li>\n<li>condition:New<\/li>\n<li>serface treatment:Polishing \/ painting\/ powder coated<\/li>\n<li>Uso: m\u00f3dulos de cremalheira de engrenagem reta 1-10<\/li>\n<li>\u00c2ngulo de press\u00e3o: 20 ou conforme desenhos<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, ce, sgs<\/li>\n<li>N\u00famero de dentes: 15<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1 M2 M3 M4 M5 M6 Cnc Gear Rack, Baoda Hoist Gear Rack in Vadodara<\/div>\n<div class=\"alpha-text1\">Export to: Serbia, Niamey, Mali, Indore etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale159.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Gear Racks 20 Pitch\/20 Pressure Angle Rack and Pinion<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: M1-M10<\/li>\n<li>Dureza: Superf\u00edcie do dente endurecida<\/li>\n<li>M\u00e9todo de fabrica\u00e7\u00e3o: Engrenagem fundida<\/li>\n<li>Material: A\u00e7o fundido<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, zincagem a quente<\/li>\n<li>Dentes helicoidais: tamb\u00e9m dispon\u00edveis<\/li>\n<li>Vantagem: Maior qualidade e menor pre\u00e7o<\/li>\n<li>Tamb\u00e9m podemos produzir como seu desenho: Sim<\/li>\n<li>Caracter\u00edsticas: com alta qualidade e baixo pre\u00e7o<\/li>\n<li>De: Cremalheira e pinh\u00e3o<\/li>\n<li>Especifica\u00e7\u00e3o: M1-M20<\/li>\n<li>C\u00f3digo SH: 8483900090<\/li>\n<li>Aplica\u00e7\u00e3o: Motor, carros el\u00e9tricos, motocicleta, m\u00e1quinas, marinha, brinquedo, m\u00e1quinas agr\u00edcolas, carro<\/li>\n<li>Posi\u00e7\u00e3o da engrenagem: Engrenagem externa<\/li>\n<li>Formato da por\u00e7\u00e3o dentada: Engrenagem reta<\/li>\n<li>Tipo: Engrenagem n\u00e3o circular<\/li>\n<li>Certificado de Qualidade: ISO9000:2008<\/li>\n<li>Caracter\u00edstica: Uso de elevadores de constru\u00e7\u00e3o e m\u00e1quinas CNC<\/li>\n<li>Cremalheira e pinh\u00e3o: cremalheira CNC<\/li>\n<li>Engrenagem de transmiss\u00e3o: cremalheira e pinh\u00e3o flex\u00edveis<\/li>\n<li>Dentes flex\u00edveis de cremalheira e pinh\u00e3o: 15<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: Xangai, China<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: M1.5 Stainlss Steel Gear Racks And Pinion in Bahrain, Small Pinion Gears in Paraguay<\/div>\n<div class=\"alpha-text1\">Export to: Bahrain, Maceio, Vadodara, Amsterdam etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Factory Direct Sales Construction Hoist (SC200\/200 SC100\/100 Success) Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:building construction materials lift for sale Model <\/p>","protected":false},"author":1,"featured_media":512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[8556,8554,1192,8552,8553,8555],"class_list":["post-2810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-baoda-hoist-gear-rack-in-vadodara","tag-cnc-rack-gear-in-maceio","tag-m1-m2-m3-m4-m5-m6-cnc-gear-rack","tag-m1-5-stainlss-steel-gear-racks-and-pinion-in-bahrain","tag-m1-5-stainlss-steel-gear-racks-and-pinion-in-faridabad","tag-small-pinion-gears-in-paraguay"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2810"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/512"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}