{"id":2677,"date":"2017-05-24T19:14:57","date_gmt":"2017-05-24T19:14:57","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/construction-mini-hoist-cranesmaterial-hoist-for-constructionconstruction-hoist-spare-parts.html"},"modified":"2017-05-24T19:14:57","modified_gmt":"2017-05-24T19:14:57","slug":"construction-mini-hoist-cranesmaterial-hoist-for-constructionconstruction-hoist-spare-parts","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/construction-mini-hoist-cranesmaterial-hoist-for-constructionconstruction-hoist-spare-parts.html","title":{"rendered":"Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale199.jpg\" alt=\"Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts\" \/><br \/>\nImage of Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:SC100\/200<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Maximum Lifting Weight:2000kg Per Cage<\/li>\n<li>Maximum Lifting Height:60m\/Min<\/li>\n<li>Lift Speed:construction hoist<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>Garantia: 3 anos<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Tipo de guindaste de torre: guindaste de constru\u00e7\u00e3o<\/li>\n<li>Instala\u00e7\u00e3o:Montado<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Gaiola: Gaiola dupla (com cabine de opera\u00e7\u00e3o ou sem cabine)<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2m,3*1,3*2,2m,3,2*1,5*2,2m (vari\u00e1vel)<\/li>\n<li>Comprimento e quantidade ajust\u00e1veis da amarra\u00e7\u00e3o de parede: 2,8-3,2 m 1 pe\u00e7a\/5 mastros (podem ser ajustados)<\/li>\n<li>Sistema el\u00e9trico principal: Schneider (pode ser equipado com sensor de falha PLC)<\/li>\n<li>type:high efficiency construction hoist<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pajB2UFFyUVV6ejg\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale336.jpg\" alt=\"Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale161.jpg\" alt=\"Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale60.jpg\" alt=\"Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale246.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Gjj Baoda Construction Hoist Parts Guide Roller Mast Section Roller<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: roller<\/li>\n<li>Movimentos: Estacion\u00e1rios<\/li>\n<li>Modo de execu\u00e7\u00e3o: estacion\u00e1rio<\/li>\n<li>Certifica\u00e7\u00e3o: GS, SGS, CE, RoHS, ISO 9001<\/li>\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Pacote de transporte: a caixa de madeira<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<li>Aplica\u00e7\u00e3o: Guindaste de constru\u00e7\u00e3o<\/li>\n<li>Tipo de acionamento: cremalheira e pinh\u00e3o<\/li>\n<li>Caracter\u00edstica: \u00c0 prova de explos\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>De: Sucesso<\/li>\n<li>Origem: Xangai<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack And Pinion in Beirut, Gear Rack For Sliding Gate<\/div>\n<div class=\"alpha-text1\">Export to: Beirut, Ghent, Lima etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale399.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">building material hoisting equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2*2000kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 36 m\/min; 0-40 m\/min; 0-60 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE, Padr\u00e3o Coreano<\/li>\n<li>Garantia: um ano ap\u00f3s o prazo de entrega<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tipo: Elevadores de constru\u00e7\u00e3o para passageiros e materiais<\/li>\n<li>Certificado: CE, ISO, GOST<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*13kw, 2*11kw, 2*15kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50Hz<\/li>\n<li>Cor: Vermelho\/laranja\/azul<\/li>\n<li>Rated Lifting speed:33m\/min<\/li>\n<li>Rack gears:40*60*1508mm<\/li>\n<li>Cage size (Inner):3*1.3*2.1m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Stainlss Steel Gear Racks in Ghent, Gear Rack For Sliding Gate Opener in Lima<\/div>\n<div class=\"alpha-text1\">Export to: Patna, Sri Lanka etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale324.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Gear rack and pinion for construction hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:SC<\/li>\n<li>Type:gear rack and pinion<\/li>\n<li>Usage:Lifting Rail for hoist\/elevator<\/li>\n<li>Specification:40*60*1507mm<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<li>Service: Installation, commissioning, Maintencem,Opration Training<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>Warranty:1 Year after delivery<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Rack And Pinion Gars in Patna, M5-M8 Gear Rack For Construction Hoist in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: Rajkot, Laos, Namibia, Beirut etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale187.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction hoist racks,lifting hoist for material handling<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB16031815, Gear Rack for Sliding Gate Operator<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60 Cremalheira para Operador de Port\u00e3o Deslizante<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais: Cremalheira para operador de port\u00e3o deslizante<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<li>\u00c2ngulo de press\u00e3o: 20 ou como desenhos<\/li>\n<li>Perfil do dente: Cremalheira para operador de port\u00e3o deslizante<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack For Sliding Gate, M5-M8 Gear Rack For Construction Hoist in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: Ottawa, Tajikistan, Namibia, Rajkot etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale317.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">M\u00f3dulos 1 a 10 Cremalheira e pinh\u00e3o de dire\u00e7\u00e3o de guincho, abridor autom\u00e1tico de port\u00e3o deslizante para elevador de constru\u00e7\u00e3o, acess\u00f3rios<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Cremalheira, Pinh\u00e3o<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>N\u00famero do modelo: M1-M10<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o, A\u00e7o C45, G60.S45, S43<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: N\u00e3o padr\u00e3o<\/li>\n<li>Perfil do dente: Engrenagem reta<\/li>\n<li>Grau: padr\u00e3o<\/li>\n<li>gear Modules:M5,M8,M10<\/li>\n<li>Modules5:30*50*1508<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<li>Modules8: 40*60*1508<\/li>\n<li>n\u00famero de dentes da engrenagem: 15<\/li>\n<li>\u00c2ngulo de press\u00e3o: 20 ou conforme desenhos<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack And Pinion in Beirut, Rack And Pinion Gars in Patna<\/div>\n<div class=\"alpha-text1\">Export to: Beirut, Lima, Sri Lanka, Laos etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Construction mini hoist cranes\/Material hoist for construction\/Construction hoist spare parts Quick Details: Condition:New Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:SC100\/200 Usage:Construction <\/p>","protected":false},"author":1,"featured_media":553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7903,1449,7905,7907,7906,7904],"class_list":["post-2677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-gear-rack-and-pinion-in-beirut","tag-gear-rack-for-sliding-gate","tag-gear-rack-for-sliding-gate-opener-in-lima","tag-m5-m8-gear-rack-for-construction-hoist-in-sri-lanka","tag-rack-and-pinion-gars-in-patna","tag-stainlss-steel-gear-racks-in-ghent"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2677"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/553"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}