{"id":2382,"date":"2017-05-22T05:08:42","date_gmt":"2017-05-22T05:08:42","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/small-plastic-gear.html"},"modified":"2017-05-22T05:08:42","modified_gmt":"2017-05-22T05:08:42","slug":"small-plastic-gear","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/small-plastic-gear.html","title":{"rendered":"small plastic gear"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale416.jpg\" alt=\"small plastic gear\" \/><br \/>\nImage of small plastic gear<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Shape:Rack Gear, rack for doors<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB15061202, M1-M20 mould rack for doors<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60<\/li>\n<li>Processing:Die Casting, Hobbing rack for doors<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Helical teeth:Also available rack for doors<\/li>\n<li>Gear:15 teeth rack for doors<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pWnl1bmFPSURPSlk\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale421.jpg\" alt=\"small plastic gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale86.jpg\" alt=\"small plastic gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale145.jpg\" alt=\"small plastic gear\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale430.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Hoist Elevator Parts, Gear Pinion<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Certification: ISO9001: 2000, CE, SGS<\/li>\n<li>Forma: Espor\u00e3o<\/li>\n<li>Tipo de dente: reto\/espiral\/esquadria<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>N\u00famero Teech: 15<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Especifica\u00e7\u00e3o: SGS<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<li>Application: Construction Usage, Workshop Usage, Container Usage, Mineral Area Usage<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Marca: Sucesso<\/li>\n<li>N\u00famero de sucesso: Tn 15<\/li>\n<li>Cor: Preto<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o<\/li>\n<li>Material: A\u00e7o<\/li>\n<li>Origem: Xangai<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: M8 Rack And Pinion in Bangladesh, Precision Gear Racks From China<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, France, La Plata etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale453.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Building Small Electric Portable Construction lift Price<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: Elevador de constru\u00e7\u00e3o SC200\/200<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO, GOST<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:Construction building lift for Passenger and materials<\/li>\n<li>Certificado: CE, ISO, GOST<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*13kw, 2*11kw, 2*15kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50Hz<\/li>\n<li>Cor: Vermelho\/laranja\/azul<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Rack And Pinion Price in France, Steel Gear Rack For Construction Hoist in La Plata<\/div>\n<div class=\"alpha-text1\">Export to: Pekanbaru, Trinidad and Tobago etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale424.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">zhangqiu quality slogan elevador de autos elevator wholesale mini 2500 electrical transformers parts building lift price<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200, SC100, SC120, SC150, SC200 (cabine dupla ou cabine simples)<\/li>\n<li>Capacidade de carga nominal (kg): 2*2000kg<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min (tipo comum)<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m (tipo comum)<\/li>\n<li>Dimens\u00e3o (C*L*A):3m*1,3m(ou1,5m)*2,4m<\/li>\n<li>Peso do carregador: 2T\/gaiola<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Certificado de qualidade: ISO9000:2008, CE<\/li>\n<li>Tipo de acionamento: cremalheira e engrenagem<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*11kw, 2*15kw, 2*13kw<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento em forno, Zincagem a quente<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>keyword:elevator<\/li>\n<li>keyword2:rack and gear<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack And Pinion For Construction Hoist in Pekanbaru, Gear Module 0.1 in Trinidad and Tobago<\/div>\n<div class=\"alpha-text1\">Export to: Pekanbaru, Liberia, Medell\u00edn, Bangladesh etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale217.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">rack and pinion gears; Straight rack &#038; Low price unique rack pinion sliding gate gear rack<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:M1 M2 M3 M4 M5 M6 M7 M8 M9 M10<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: C45<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>cor:preto<\/li>\n<li>D\/C:Precision Gear Rack<\/li>\n<li>Package:wooden case<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Precision Gear Racks From China, Gear Module 0.1 in Trinidad and Tobago<\/div>\n<div class=\"alpha-text1\">Export to: Colombo, Zambia, Medell\u00edn, Pekanbaru etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale93.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Gear Rack and Pinion for Sliding Door<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Tipo: Engrenagem de cremalheira<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO9001: 2000, SGS<\/li>\n<li>Tamanho: 40*60*1508<\/li>\n<li>M\u00f3dulo: 5m,8m<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Pacote de transporte: embalagem de madeira<\/li>\n<li>Origem: Xangai<\/li>\n<li>Aplica\u00e7\u00e3o: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Dente: 60<\/li>\n<li>Tratamento de superf\u00edcie: galvanizado, preto<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: CE+SGS<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: M8 Rack And Pinion in Bangladesh, Gear Rack And Pinion For Construction Hoist in Pekanbaru<\/div>\n<div class=\"alpha-text1\">Export to: Bangladesh, La Plata, Trinidad and Tobago, Liberia etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of small plastic gear Quick Details: Shape:Rack Gear, rack for doors Place of Origin:Shanghai, China (Mainland) Model Number:RB15061202, M1-M20 mould rack for doors Brand <\/p>","protected":false},"author":1,"featured_media":280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6727,6726,6723,2374,6724,6725],"class_list":["post-2382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-gear-module-0-1-in-trinidad-and-tobago","tag-gear-rack-and-pinion-for-construction-hoist-in-pekanbaru","tag-m8-rack-and-pinion-in-bangladesh","tag-precision-gear-racks-from-china","tag-rack-and-pinion-price-in-france","tag-steel-gear-rack-for-construction-hoist-in-la-plata"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2382"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}