{"id":2096,"date":"2017-05-21T23:17:24","date_gmt":"2017-05-21T23:17:24","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/drill-press-rack-piniondrill-press-rack.html"},"modified":"2017-05-21T23:17:24","modified_gmt":"2017-05-21T23:17:24","slug":"drill-press-rack-piniondrill-press-rack","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/drill-press-rack-piniondrill-press-rack.html","title":{"rendered":"drill press rack pinion,drill press rack"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale391.jpg\" alt=\"drill press rack pinion,drill press rack\" \/><br \/>\nImage of drill press rack pinion,drill press rack<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB15052009M8, cnc rack and pinion gears<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, a\u00e7o, C45, G60 cnc cremalheira e pinh\u00e3o engrenagens<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais: engrenagens de cremalheira e pinh\u00e3o CNC<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<li>\u00c2ngulo de press\u00e3o: 20 ou como desenhos<\/li>\n<li>Perfil do dente: Engrenagens de cremalheira e pinh\u00e3o CNC de engrenagem reta<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pbXlPQjNrRmZDUW8\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale207.jpg\" alt=\"drill press rack pinion,drill press rack\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale277.jpg\" alt=\"drill press rack pinion,drill press rack\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale212.jpg\" alt=\"drill press rack pinion,drill press rack\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale431.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">1: 16 Reduction Gearbox for Construction Hoist Parts<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: 1: 16<\/li>\n<li>Dureza: Superf\u00edcie do dente endurecida<\/li>\n<li>Layout: Coaxial<\/li>\n<li>Step: Single-Step<\/li>\n<li>N\u00famero de sucesso: 16: 1, 12: 1, 10: 1<\/li>\n<li>Pot\u00eancia nominal: 11,02\/11,06 kW<\/li>\n<li>Caixa de velocidades: 1:16<\/li>\n<li>Uso: Caixa de engrenagens do elevador<\/li>\n<li>Marca Pr\u00f3pria: Caixa de Engrenagens para Elevadores Dispon\u00edvel<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: SGS, CE, CCC, ISO<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<li>Application: Motor, Machinery<\/li>\n<li>Installation: Horizontal Type<\/li>\n<li>Gear Shape: Conical &#8211; Cylindrical Gear<\/li>\n<li>Type: Planetary Gear Reducer<\/li>\n<li>Torque de sa\u00edda: 800\/960 nm<\/li>\n<li>Velocidade de entrada: 1500\/min<\/li>\n<li>Pot\u00eancia: 11kw, 15kw, 18kw Caixa de engrenagens do elevador<\/li>\n<li>Peso de eleva\u00e7\u00e3o: 2t e mais Caixa de engrenagens do elevador<\/li>\n<li>Fonte: El\u00e9trica<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: Xangai<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Gears Module 5 in Chile, Worm Drive<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Dallas, Jodhpur etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale342.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">SC200\/200 Frequency conversion construction hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o, especial para edif\u00edcios altos para levantar carga e passageiros<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2*2000kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 250 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 36 m\/min; 0-40 m\/min; 0-60 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: ISO, CE, Padr\u00e3o Coreano<\/li>\n<li>Garantia: um ano ap\u00f3s o prazo de entrega<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:Construction Lift for Passenger and materials<\/li>\n<li>Certificado de qualidade: ISO9000:2008, CE<\/li>\n<li>Tipo de transmiss\u00e3o: Engrenagem e cremalheira<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento em forno, Zincagem a quente<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*11kw, 2*15kw, 2*13kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50hz Pode ser alterado conforme sua necessidade<\/li>\n<li>Servi\u00e7o: Instala\u00e7\u00e3o, comissionamento, manuten\u00e7\u00e3o, treinamento operacional<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Racks And Pinions For Cnc Machines in Dallas, Cnc Machine Rack Gears in Jodhpur<\/div>\n<div class=\"alpha-text1\">Export to: Ranchi, Yaound\u00e9 etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale21.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">material handling equipment<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Forma da Viga Principal: Viga Dupla<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Tipo de guindaste de torre: guindaste de constru\u00e7\u00e3o<\/li>\n<li>Instala\u00e7\u00e3o:Montado<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Gaiola: Gaiola dupla (com cabine de opera\u00e7\u00e3o ou sem cabine)<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2m,3*1,3*2,2m,3,2*1,5*2,2m (vari\u00e1vel)<\/li>\n<li>Comprimento e quantidade ajust\u00e1veis da amarra\u00e7\u00e3o de parede: 2,8-3,2 m 1 pe\u00e7a\/5 mastros (podem ser ajustados)<\/li>\n<li>Sistema el\u00e9trico principal: Schneider (pode ser equipado com sensor de falha PLC)<\/li>\n<li>Feature:SC200\/200 construction lift hoist<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Rack And Pinion Lift in Ranchi, Gear Rack And Pinion Design For Cnc Machine in Yaound\u00e9<\/div>\n<div class=\"alpha-text1\">Export to: Agra, Jamaica, Santiago, Chile etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale132.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Rack and gear parts for construction \/building hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:M8<\/li>\n<li>Marca: GJJ<\/li>\n<li>Material: A\u00e7o<\/li>\n<li>Processing:Forging<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Hardness:230<\/li>\n<li>Tensile strength:764<\/li>\n<li>Yield strength:461<\/li>\n<li>Surface treatment:Blacking<\/li>\n<li>Size:40*60*1508mm<\/li>\n<li>Packing:Pallet<\/li>\n<li>MOQ:200pcs<\/li>\n<li>Loading port:Shanghai<\/li>\n<li>Payment:100% TT<\/li>\n<li>Hole size:M16<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Worm Drive, Gear Rack And Pinion Design For Cnc Machine in Yaound\u00e9<\/div>\n<div class=\"alpha-text1\">Export to: Papua New Guinea, Tangier, Santiago, Agra etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale204.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction Passenger Hoist Overload Indicator and Sensor<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: KQC-C2<\/li>\n<li>Component: Mechanical Structure Type<\/li>\n<li>Output Signal Type: Digital Type<\/li>\n<li>Material: Plastic<\/li>\n<li>Wiring Type: Three-Wire<\/li>\n<li>IP Rating: IP56<\/li>\n<li>Customized: Customized<\/li>\n<li>Rated Power: 5W<\/li>\n<li>Working Temperature: -20 to 60&ordm;C<\/li>\n<li>Comprehensive Error: Less Than 1% F.S<\/li>\n<li>Buzzer: up to 90dB<\/li>\n<li>Sensor Working Voltage: DC5-12V<\/li>\n<li>Transport Package: Carton Box<\/li>\n<li>Origem: China<\/li>\n<li>Type: Inductive Pressure Sensor<\/li>\n<li>For: Passenger Hoist<\/li>\n<li>Production Process: Ceramics<\/li>\n<li>Thread Type: G<\/li>\n<li>Measuring Medium: Steam<\/li>\n<li>Certification: CE<\/li>\n<li>Success: in-318<\/li>\n<li>Working Voltage: AC180-260V<\/li>\n<li>Opetation Humidity: 95%<\/li>\n<li>Alarm Output: AC250V\/7A<\/li>\n<li>Sensitivity of The Sensor: 1.0000 Mv\/V<\/li>\n<li>From: KQC<\/li>\n<li>Specification: metal<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Gears Module 5 in Chile, Rack And Pinion Lift in Ranchi<\/div>\n<div class=\"alpha-text1\">Export to: Chile, Jodhpur, Yaound\u00e9, Jamaica etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of drill press rack pinion,drill press rack Quick Details: Shape:Rack Gear, Rack Gear Place of Origin:Shanghai, China (Mainland) Model Number:RB15052009M8, cnc rack and pinion <\/p>","protected":false},"author":1,"featured_media":282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6357,6359,6356,6355,6358,2255],"class_list":["post-2096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-cnc-machine-rack-gears-in-jodhpur","tag-gear-rack-and-pinion-design-for-cnc-machine-in-yaounde","tag-gear-racks-and-pinions-for-cnc-machines-in-dallas","tag-gears-module-5-in-chile","tag-rack-and-pinion-lift-in-ranchi","tag-worm-drive"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=2096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}