{"id":1962,"date":"2017-05-21T05:44:24","date_gmt":"2017-05-21T05:44:24","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/construction-hoist-rackslifting-machine.html"},"modified":"2017-05-21T05:44:24","modified_gmt":"2017-05-21T05:44:24","slug":"construction-hoist-rackslifting-machine","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/construction-hoist-rackslifting-machine.html","title":{"rendered":"Construction hoist racks,lifting machine"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale113.jpg\" alt=\"Construction hoist racks,lifting machine\" \/><br \/>\nImage of Construction hoist racks,lifting machine<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB2015072707, M1-M20 mould spur gear racks helical gear rack<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60<\/li>\n<li>Processing:Die Casting, Hobbing spur gear racks helical gear rack<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Helical teeth:Also available spur gear racks helical gear rack<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pRk1NdzVBeEdRRk0\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale500.jpg\" alt=\"Construction hoist racks,lifting machine\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale54.jpg\" alt=\"Construction hoist racks,lifting machine\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale381.jpg\" alt=\"Construction hoist racks,lifting machine\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale443.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Overload Protector for Construction Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: KQC-C2<\/li>\n<li>Aplica\u00e7\u00e3o: Uso na constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Working Voltage: AC180-260V<\/li>\n<li>Voltage Rating: 5W<\/li>\n<li>Warranty: 1 Year<\/li>\n<li>Passenger: 2*16<\/li>\n<li>Origem: Xangai<\/li>\n<li>Tipo: Plataforma Elevat\u00f3ria<\/li>\n<li>Tipo de eslinga: cabo de a\u00e7o<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001: 2000<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Success Number: Kqc-C2<\/li>\n<li>Load Rating: 2t<\/li>\n<li>Display Mode: 6 Digital Display<\/li>\n<li>Drive Type: Gear and Rack<\/li>\n<li>Especifica\u00e7\u00e3o: SGS<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Rack Pinion Gear in Bari, G60 Steel Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Fortress, Mauritania etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale495.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Single\/Twin Mast Climbing platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:SC100\/100<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o, especial para edif\u00edcios altos para levantar carga e passageiros<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 2000 kg<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150 m<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 33 m\/min<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9000, CE, Padr\u00e3o Internacional da Coreia<\/li>\n<li>Garantia: um ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Type:Single\/Twin Mast Climbing platform<\/li>\n<li>Tipo de acionamento: cremalheira e engrenagem<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Servi\u00e7o: Instala\u00e7\u00e3o, comissionamento, manuten\u00e7\u00e3o, treinamento operacional<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Acabamento em forno, Zincagem a quente<\/li>\n<li>Cor: Vermelho\/laranja\/azul\/sua exig\u00eancia<\/li>\n<li>Motor power:2*11kw*2<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50hz Pode ser alterado conforme sua necessidade<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Nylon Tooth Gear Rack in Fortress, M8 Hoist Rack in Mauritania<\/div>\n<div class=\"alpha-text1\">Export to: Nepal, Valencia etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale9.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">gjj roller for passenger hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca: Elevador de constru\u00e7\u00e3o\/elevador de materiais de constru\u00e7\u00e3o\/elevador\/material de constru\u00e7\u00e3o<\/li>\n<li>Model Number:Construction elevatorM3<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Fonte de energia: El\u00e9trica<\/li>\n<li>Tipo de eslinga: cabo<\/li>\n<li>Peso m\u00e1ximo de eleva\u00e7\u00e3o: 1T-20T<\/li>\n<li>Altura m\u00e1xima de eleva\u00e7\u00e3o: 150M<\/li>\n<li>Velocidade de eleva\u00e7\u00e3o: 36M\/MIN<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>Garantia: 1 ano<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Tower Crane Type:gjj passenger hoist guide roller<\/li>\n<li>SC200\/200::gjj passenger hoist guide roller<\/li>\n<li>Tipo de movimenta\u00e7\u00e3o: cremalheira e engrenagem<\/li>\n<li>Main Girder Form:Double Girder gjj passenger hoist guide roller<\/li>\n<li>Gaiola: Gaiola dupla (com opera\u00e7\u00e3o<\/li>\n<li>Sistema El\u00e9trico Principal: Schneider<\/li>\n<li>Installation:Assembled gjj passenger hoist guide roller<\/li>\n<li>Comprimento ajust\u00e1vel da amarra\u00e7\u00e3o de parede e quantidade: 2,8-3,2 m 1 pe\u00e7a\/5 mastros<\/li>\n<li>Dimens\u00e3o da gaiola: 3*1,5*2,2 m, 3*1,3*2,2 m<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gjj Hoist Rack in Nepal, M8 Rack Elevator in Valencia<\/div>\n<div class=\"alpha-text1\">Export to: Padang, Lebanon, Tegucigalpa, Bari etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale38.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction hoist racks,lifting machine<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB15102001, M1-M20 mould<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: C45, A\u00e7o, C45, G60<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais:Tamb\u00e9m dispon\u00edvel<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: G60 Steel Gear Rack, M8 Rack Elevator in Valencia<\/div>\n<div class=\"alpha-text1\">Export to: Philadelphia, Lagos, Tegucigalpa, Padang etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale447.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Cremalheira e pinh\u00e3o para elevador de constru\u00e7\u00e3o, Pot\u00eancia mec\u00e2nica<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>N\u00famero do modelo: RB15051210, molde M1-M20<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais:Tamb\u00e9m dispon\u00edvel<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Rack Pinion Gear in Bari, Gjj Hoist Rack in Nepal<\/div>\n<div class=\"alpha-text1\">Export to: Bari, Mauritania, Valencia, Lebanon etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Construction hoist racks,lifting machine Quick Details: Shape:Rack Gear, Rack Gear Place of Origin:Shanghai, China (Mainland) Model Number:RB2015072707, M1-M20 mould spur gear racks helical <\/p>","protected":false},"author":1,"featured_media":108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2226,5710,5709,5711,5708,5707],"class_list":["post-1962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-g60-steel-gear-rack","tag-gjj-hoist-rack-in-nepal","tag-m8-hoist-rack-in-mauritania","tag-m8-rack-elevator-in-valencia","tag-nylon-tooth-gear-rack-in-fortress","tag-rack-pinion-gear-in-bari"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=1962"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/108"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=1962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=1962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=1962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}