{"id":1848,"date":"2017-05-19T20:26:26","date_gmt":"2017-05-19T20:26:26","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/gearboxsmall-rack-gear.html"},"modified":"2017-05-19T20:26:26","modified_gmt":"2017-05-19T20:26:26","slug":"gearboxsmall-rack-gear","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/gearboxsmall-rack-gear.html","title":{"rendered":"gearbox,small rack gear"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale416.jpg\" alt=\"gearbox,small rack gear\" \/><br \/>\nImage of gearbox,small rack gear<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Arranjo de engrenagens: sem-fim, chanfro\/esquadria<\/li>\n<li>Torque de sa\u00edda: redutor de engrenagem sem-fim, redutor de velocidade<\/li>\n<li>Pot\u00eancia nominal: redutor de velocidade, 10-19 kW<\/li>\n<li>Velocidade de entrada: caixa de redu\u00e7\u00e3o do motor el\u00e9trico<\/li>\n<li>Velocidade de sa\u00edda: redutor de engrenagem helicoidal, 852-3900 Nm<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB15101209<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material do eixo: a\u00e7o forjado de 40cr<\/li>\n<li>Material da engrenagem helicoidal: 20crmntih e 17crnimo 6<\/li>\n<li>Carca\u00e7a de engrenagens: Ferro fundido (Ht250 ou Qt450)<\/li>\n<li>Posi\u00e7\u00e3o de montagem: M1, M2, M3, M4, M5, M6<\/li>\n<li>Caracter\u00edsticas: redutor, redutor de engrenagem sem-fim<\/li>\n<li>Certificado: ISO9001: 2000 CE CCC<\/li>\n<li>Nome: redutor de engrenagem sem-fim, redutor de velocidade<\/li>\n<li>Dureza da engrenagem helicoidal: Hrc58-62<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pSWNzcm0yWXNjcnc\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale219.jpg\" alt=\"gearbox,small rack gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale123.jpg\" alt=\"gearbox,small rack gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale485.jpg\" alt=\"gearbox,small rack gear\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale401.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Gear Rack and Pinion for Construction Hoist with Top Quality<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Sucesso N\u00ba: M8 M6 M5 M4<\/li>\n<li>Dureza: Superf\u00edcie do dente endurecida<\/li>\n<li>Manufacturing Method: Cut Gear<\/li>\n<li>Material: A\u00e7o fundido<\/li>\n<li>Marca: Sucesso<\/li>\n<li>Dispositivo de seguran\u00e7a para elevadores de constru\u00e7\u00e3o: Dispositivo de seguran\u00e7a<\/li>\n<li>Dispositivo de eleva\u00e7\u00e3o: talha el\u00e9trica<\/li>\n<li>Caracter\u00edsticas: Cremalheira com maior<\/li>\n<li>N\u00famero de dentes: 15 dentes padr\u00e3o<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<li>Origem: Xangai<\/li>\n<li>Application: Motor, Electric Cars, Motorcycle, Machinery, Marine, Toy, Agricultural Machinery, Car, Construction Hoist<\/li>\n<li>Posi\u00e7\u00e3o da engrenagem: Engrenagem externa<\/li>\n<li>Formato da por\u00e7\u00e3o dentada: Engrenagem reta<\/li>\n<li>Tipo: Engrenagem n\u00e3o circular<\/li>\n<li>N\u00famero de sucesso: M1-M10<\/li>\n<li>Elevador de constru\u00e7\u00e3o: Cremalheira<\/li>\n<li>Dispositivo de seguran\u00e7a para elevador: Motor<\/li>\n<li>Dispositivo de seguran\u00e7a do elevador: Redutor<\/li>\n<li>De: Sucesso<\/li>\n<li>Especifica\u00e7\u00e3o: cerca de 7 a 15 dias ap\u00f3s o recebimento do pagamento<\/li>\n<li>C\u00f3digo SH: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Flexible Gear Rack in Belarus, Pinion Gear And Rack<\/div>\n<div class=\"alpha-text1\">Export to: Belarus, Guayaquil, Japan etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale229.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">2015 Modules 1 Gear Rack for Construction Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, Fundi\u00e7\u00e3o sob press\u00e3o, Fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>superf\u00edcie: cor natural\\tinta\\escurecimento\\galvanizado<\/li>\n<li>Nome: cremalheira<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Nylon Plastic Gear Rack in Guayaquil, Gear Box in Japan<\/div>\n<div class=\"alpha-text1\">Export to: Osaka, Sri Lanka etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale427.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">elevadores residenciais externos de novo tipo sc<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Tipo: Elevadores, Elevadores de passageiros e materiais<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>N\u00famero do modelo: SC200\/200<\/li>\n<li>Uso: Empresa l\u00edder na China em elevadores de constru\u00e7\u00e3o<\/li>\n<li>Tipo de acionamento: cremalheira e pinh\u00e3o<\/li>\n<li>Tipo de elevador: Elevadores de mercadorias<\/li>\n<li>Certificado: CE, ISO, GOST<\/li>\n<li>Tipo de acionamento: Engrenagem e cremalheira<\/li>\n<li>Sistema el\u00e9trico principal: Schneider<\/li>\n<li>Pot\u00eancia do motor: 3*11kw, 2*13kw, 2*11kw, 2*15kw<\/li>\n<li>Voltagem\/Frequ\u00eancia: 380v\/50Hz<\/li>\n<li>Se\u00e7\u00e3o do mastro: 650*650*1508 mm (grau de a\u00e7o: 20#, di\u00e2metro 76\u00d74,5 mm e 6,0 mm)<\/li>\n<li>Cor: Vermelho\/laranja\/azul<\/li>\n<li>Experi\u00eancia de produ\u00e7\u00e3o: 8 anos<\/li>\n<li>Taxa de carga do guindaste de montagem: 2*2000Kg<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gear Rack Motor in Osaka, Brass Worm Gear in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: Gabon, Prague, Goiania, Belarus etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale364.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">plastic pinion helical gear\/rack and pinion\/CNC Hyundai Steering gear rack and pinion<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>N\u00famero do modelo: M1-M10<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o inoxid\u00e1vel, C45<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Uso: Elevador de constru\u00e7\u00e3o<\/li>\n<li>cor:preto<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Pinion Gear And Rack, Brass Worm Gear in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: Philadelphia, Alexandria, Goiania, Gabon etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale431.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction hoist racks,flexible gear racks<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, Engrenagem de cremalheira<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:RB15121614, M1-M20 mould<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: A\u00e7o, A\u00e7o, C45, G60<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o<\/li>\n<li>Certificado de qualidade: ISO9000:2008<\/li>\n<li>Dentes helicoidais:Tamb\u00e9m dispon\u00edvel<\/li>\n<li>Engrenagem: 15 dentes<\/li>\n<li>Tratamento de superf\u00edcie: Jateamento, Zincagem a quente<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Flexible Gear Rack in Belarus, Gear Rack Motor in Osaka<\/div>\n<div class=\"alpha-text1\">Export to: Belarus, Japan, Sri Lanka, Prague etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of gearbox,small rack gear Quick Details: Gearing Arrangement:Worm, Bevel \/ Miter Output Torque:worm gear reducer, speed reducer Rated Power:speed reducer,10-19KW Input Speed:electric motor reduction <\/p>","protected":false},"author":1,"featured_media":314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5235,5231,5233,5234,5232,552],"class_list":["post-1848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-brass-worm-gear-in-sri-lanka","tag-flexible-gear-rack-in-belarus","tag-gear-box-in-japan","tag-gear-rack-motor-in-osaka","tag-nylon-plastic-gear-rack-in-guayaquil","tag-pinion-gear-and-rack"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=1848"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=1848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=1848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=1848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}