{"id":1812,"date":"2017-05-19T08:12:28","date_gmt":"2017-05-19T08:12:28","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/motor-for-construction-hoistsmall-rack-gear.html"},"modified":"2017-05-19T08:12:28","modified_gmt":"2017-05-19T08:12:28","slug":"motor-for-construction-hoistsmall-rack-gear","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/pt\/motor-for-construction-hoistsmall-rack-gear.html","title":{"rendered":"Motor for construction hoist,small rack gear"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale454.jpg\" alt=\"Motor for construction hoist,small rack gear\" \/><br \/>\nImage of Motor for construction hoist,small rack gear<\/p>\n<h3 class=\"alpha-title\">Detalhes r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:RB16031403<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Place of origin:china<\/li>\n<li>Private label:available<\/li>\n<li>Power:11KW, 15KW, 18KW<\/li>\n<li>Brand name:Success<\/li>\n<li>Model number:Success motor<\/li>\n<li>Usage:Construction hoist<\/li>\n<li>Source:Eletric<\/li>\n<li>Sling type:Cable<\/li>\n<li>Lifting weight:2T and more<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pY3ZNRVJ0ZV9YdDA\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descri\u00e7\u00e3o: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale326.jpg\" alt=\"Motor for construction hoist,small rack gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale116.jpg\" alt=\"Motor for construction hoist,small rack gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale252.jpg\" alt=\"Motor for construction hoist,small rack gear\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Deixe um recado: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Voc\u00ea tamb\u00e9m pode gostar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale103.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Tower Crane Spare Parts Protection System<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Tipo: Dispositivo de seguran\u00e7a<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO9001: 2000<\/li>\n<li>Installation: 360 Degree All-Round Rack Mounting<\/li>\n<li>De: CPTC<\/li>\n<li>Origem: China<\/li>\n<li>Application: Tower Crane<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Maximum Lifting Height: 250m<\/li>\n<li>Pacote de transporte: caixa de madeira<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Precisoin Gear Rack in Cairo, Spur Gear Rack And Pinion<\/div>\n<div class=\"alpha-text1\">Export to: Cairo, Guarulhos, Jerusalem etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale336.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Power Transmission Cnc Steel Round Gear Rack Aluminum Gear Rack Spur Rack Gears<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, espora<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Model Number:rack<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o, Metal<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o, Fundi\u00e7\u00e3o sob press\u00e3o, Fresagem<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: Padr\u00e3o, Padr\u00e3o<\/li>\n<li>superf\u00edcie: cor natural\\tinta\\escurecimento\\galvanizado<\/li>\n<li>Nome: Cremalheira<\/li>\n<li>Perfil do dente: Helicoidal<\/li>\n<li>M\u00f3dulo: M1-M10<\/li>\n<li>Comprimento:Personaliza\u00e7\u00e3o<\/li>\n<li>Largura:Personaliza\u00e7\u00e3o<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Steel Gear Racks Construction Elevator in Guarulhos, Wire Rope in Jerusalem<\/div>\n<div class=\"alpha-text1\">Export to: Sao Goncalo, Warsaw etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale331.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Driver board Baoda Driving Device Lifting Equipment Construction Motor<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Model Number:RB16031415M5<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Place of origin:china<\/li>\n<li>Private label:available<\/li>\n<li>Power:11KW, 15KW, 18KW<\/li>\n<li>Brand name:Success<\/li>\n<li>Model number:Success motor<\/li>\n<li>Usage:Construction hoist<\/li>\n<li>Source:Eletric<\/li>\n<li>Sling type:Cable<\/li>\n<li>Lifting weight:2T and more<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Steel Gear Rack For Construction Hoist in Sao Goncalo, Gears Module 5 in Warsaw<\/div>\n<div class=\"alpha-text1\">Export to: Rostov-on-Don, Luxembourg, Belo Horizonte, Cairo etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale80.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">professional design gear rack and pinion,worm gear and rack<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engrenagem de cremalheira, engrenagens de cremalheira e pinh\u00e3o<\/li>\n<li>Local de origem: Xangai, China (continental)<\/li>\n<li>N\u00famero do modelo: M1-M10<\/li>\n<li>Marca:Sucesso<\/li>\n<li>Material: A\u00e7o, A\u00e7o C45, G60.S45, S43<\/li>\n<li>Processamento: Fundi\u00e7\u00e3o sob press\u00e3o<\/li>\n<li>Padr\u00e3o ou n\u00e3o padr\u00e3o: N\u00e3o padr\u00e3o<\/li>\n<li>cor:preto<\/li>\n<li>Grau: padr\u00e3o<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Uso:pre\u00e7o de cremalheira e pinh\u00e3o<\/li>\n<li>Servi\u00e7o p\u00f3s-venda fornecido: Engenheiros dispon\u00edveis para fazer manuten\u00e7\u00e3o de m\u00e1quinas no exterior<\/li>\n<li>Certifica\u00e7\u00e3o: ISO9001:2008<\/li>\n<li>M\u00f3dulos: M1-M10<\/li>\n<li>N\u00famero de dentes: 15<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Spur Gear Rack And Pinion, Gears Module 5 in Warsaw<\/div>\n<div class=\"alpha-text1\">Export to: New York, Kinshasa, Belo Horizonte, Rostov-on-Don etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale17.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Mast Section of Sc200\/200 Construction Material Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: 650*650*1508<\/li>\n<li>Aplica\u00e7\u00e3o: Elevador de constru\u00e7\u00e3o<\/li>\n<li>Condi\u00e7\u00e3o: Novo<\/li>\n<li>Size: 650*650*1508mm<\/li>\n<li>Drive Type: Gear and Rack<\/li>\n<li>De: Sucesso<\/li>\n<li>Specification: 650*650*1508<\/li>\n<li>C\u00f3digo SH: 8431390000<\/li>\n<li>Type: Mast Section<\/li>\n<li>Certifica\u00e7\u00e3o: CE, ISO9001: 2000, SGS<\/li>\n<li>Material: Q345,Q234<\/li>\n<li>Surface Treatment: Spray Paint ,Hot Dipping Zinc<\/li>\n<li>Max Lifting Height: 300m<\/li>\n<li>Transport Package: Container<\/li>\n<li>Origem: China<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Precisoin Gear Rack in Cairo, Steel Gear Rack For Construction Hoist in Sao Goncalo<\/div>\n<div class=\"alpha-text1\">Export to: Cairo, Jerusalem, Warsaw, Luxembourg etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Deixe um recado<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of Motor for construction hoist,small rack gear Quick Details: Place of Origin:Shanghai, China (Mainland) Brand Name:Success Model Number:RB16031403 Condition:New Place of origin:china Private label:available <\/p>","protected":false},"author":1,"featured_media":507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5054,5050,276,5053,5051,5052],"class_list":["post-1812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-gears-module-5-in-warsaw","tag-precisoin-gear-rack-in-cairo","tag-spur-gear-rack-and-pinion","tag-steel-gear-rack-for-construction-hoist-in-sao-goncalo","tag-steel-gear-racks-construction-elevator-in-guarulhos","tag-wire-rope-in-jerusalem"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/comments?post=1812"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/posts\/1812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media\/507"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/media?parent=1812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/categories?post=1812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/pt\/wp-json\/wp\/v2\/tags?post=1812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}