{"id":4073,"date":"2017-06-06T08:54:43","date_gmt":"2017-06-06T08:54:43","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/harvester-dongfeng-truck-gear.html"},"modified":"2017-06-06T08:54:43","modified_gmt":"2017-06-06T08:54:43","slug":"harvester-dongfeng-truck-gear","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/es\/harvester-dongfeng-truck-gear.html","title":{"rendered":"harvester dongfeng truck gear"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale334.jpg\" alt=\"harvester dongfeng truck gear\" \/><br \/>\nImage of harvester dongfeng truck gear<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Forma: Espuela<\/li>\n<li>Lugar de origen: \u00c9xito, China (Continental), \u00c9xito, China (Continental)<\/li>\n<li>N\u00famero de modelo: personalizado<\/li>\n<li>Nombre de la marca: OEM<\/li>\n<li>Material: acero, acero, acero C45<\/li>\n<li>Forma: Cremallera, cuadrada<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar:Est\u00e1ndar<\/li>\n<li>Palabras clave: Engranaje<\/li>\n<li>Procesamiento: Tallado a mano<\/li>\n<li>Embalaje: seg\u00fan la solicitud de nuestro cliente.<\/li>\n<li>Perfil del diente: seg\u00fan solicitud<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02paFBWMnItNnhhczQ\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale162.jpg\" alt=\"harvester dongfeng truck gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale190.jpg\" alt=\"harvester dongfeng truck gear\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale494.jpg\" alt=\"harvester dongfeng truck gear\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale244.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Automatic Gate Gear Rack\/Construction Hoist\/Worm Gear and Rack<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: M5\/M6\/M8\/M9<\/li>\n<li>Texture: G60<\/li>\n<li>Color: Negro<\/li>\n<li>Dispositivo de seguridad para ascensor: Motor<\/li>\n<li>Dispositivo de seguridad del ascensor: Reductor<\/li>\n<li>N\u00famero de dientes: 15 dientes est\u00e1ndar<\/li>\n<li>Paquete de transporte: Caja de madera<\/li>\n<li>Origen: Shangh\u00e1i<\/li>\n<li>Success Number: M8<\/li>\n<li>Uso: Polipasto de construcci\u00f3n<\/li>\n<li>Pieza del ascensor de construcci\u00f3n: Cremallera<\/li>\n<li>Dispositivo de seguridad para ascensores de construcci\u00f3n: Dispositivo de seguridad<\/li>\n<li>Dispositivo de elevaci\u00f3n: polipasto el\u00e9ctrico<\/li>\n<li>De: \u00c9xito<\/li>\n<li>Specification: SGS, CE, CCC<\/li>\n<li>C\u00f3digo HS: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: M8 Construction Hoist Gear Rack in Australia, Lg60 M8 Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Australia, Colombia, Kota etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale361.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Heavy construction building machine building outdoor elevator<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: SC200\/200, SC150\/150, SCA200\/200<\/li>\n<li>Capacidad de carga nominal (kg): 1000 kg-2000 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 250 m<\/li>\n<li>Dimensiones (largo x ancho x alto): 3,0 x 1,3 (1,5) x 2,2<\/li>\n<li>Peso del cargador: 2000 kg<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Type:building outdoor elevator<\/li>\n<li>Voltaje-frecuencia: 380-50 HZ (se puede organizar seg\u00fan los requisitos del cliente)<\/li>\n<li>Velocidad de elevaci\u00f3n: 33 m\/min, 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Capacidad nominal: 1000 kg \u2013 2000 kg<\/li>\n<li>Potencia del motor: 11 kW*2, 11 kW*3, 15 kW*2, 12 kW*2, 13 kW*2<\/li>\n<li>Certificaci\u00f3n: ISO9000, CE, GOST, est\u00e1ndar de Corea<\/li>\n<li>Secci\u00f3n del m\u00e1stil: 650 x 650 x 1508 (mm) Peso: 145 kg<\/li>\n<li>Tipo de accionamiento: engranaje y cremallera<\/li>\n<li>Tratamiento de superficie: Granallado, acabado horneado, galvanizado, pintura.<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Gjj M5 Gear Rack in Colombia, Steel Gear Rack in Kota<\/div>\n<div class=\"alpha-text1\">Export to: Phoenix, Sri Lanka etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale154.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE Approved Building Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca: polipasto para materiales de construcci\u00f3n<\/li>\n<li>N\u00famero de modelo: polipasto para materiales de construcci\u00f3n<\/li>\n<li>Uso: Polipasto de construcci\u00f3n<\/li>\n<li>Fuente de energ\u00eda: el\u00e9ctrica<\/li>\n<li>Tipo de eslinga: cable<\/li>\n<li>Peso m\u00e1ximo de elevaci\u00f3n: 1T-20T<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 150 m<\/li>\n<li>Velocidad de elevaci\u00f3n: 36 m\/min<\/li>\n<li>Certificaci\u00f3n: ISO9001:2008<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Tower Crane Type:used passenger lifts<\/li>\n<li>SC200\/200::used passenger lifts<\/li>\n<li>Tipo de movimiento: Bastidor y engranaje<\/li>\n<li>Forma de la viga principal: viga doble<\/li>\n<li>Jaula: Jaula doble (con operaci\u00f3n)<\/li>\n<li>Sistema el\u00e9ctrico principal: Schneider<\/li>\n<li>Instalaci\u00f3n:Ensamblado<\/li>\n<li>Longitud y cantidad ajustables para amarres de pared: 2,8-3,2 m, 1 pieza\/5 m\u00e1stiles<\/li>\n<li>Cage Dimension:3*1.5*2.2m,3*1.3*2.2m used passenger lifts<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M1 M2 M3 M4 M5 M6 Cnc Gear Rack in Phoenix, Wire Rope in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: India , Birmingham, Mali, Australia etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale32.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Construction hoist racks,CNC Machine stainless steel round gear rack and pinion<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engranaje de cremallera, engranaje de cremallera<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Model Number:RB15121715, M1-M20 mould<\/li>\n<li>Marca: GJJ, BAODA, Success<\/li>\n<li>Material: acero, acero, C45, G60<\/li>\n<li>Procesamiento:Fundici\u00f3n a presi\u00f3n, tallado<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar:Est\u00e1ndar<\/li>\n<li>Certificado de calidad: ISO9000:2008<\/li>\n<li>Dientes helicoidales:Tambi\u00e9n disponibles<\/li>\n<li>Engranaje: 15 dientes<\/li>\n<li>Tratamiento de superficie: Granallado, galvanizado en caliente.<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Lg60 M8 Gear Rack, Wire Rope in Sri Lanka<\/div>\n<div class=\"alpha-text1\">Export to: Somalia, Turkey, Mali, India  etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale478.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Modules 1 Gear Rack for Construction Hoist<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Forma: Engranaje de cremallera<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>N\u00famero de modelo: M1-M10<\/li>\n<li>Marca:Success<\/li>\n<li>Material: acero<\/li>\n<li>Procesamiento:Fundici\u00f3n a presi\u00f3n<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar:No est\u00e1ndar<\/li>\n<li>color: negro<\/li>\n<li>grade:Standard<\/li>\n<li>Modules:M1-110<\/li>\n<li>Features:Gear Rack for Construction Hoist<\/li>\n<li>Usage:rack gear<\/li>\n<li>Tipo de accionamiento: Cremallera y pi\u00f1\u00f3n<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: M8 Construction Hoist Gear Rack in Australia, M1 M2 M3 M4 M5 M6 Cnc Gear Rack in Phoenix<\/div>\n<div class=\"alpha-text1\">Export to: Australia, Kota, Sri Lanka, Birmingham etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of harvester dongfeng truck gear Quick Details: Shape:Spur Place of Origin:Success, China (Mainland), Success, China (Mainland) Model Number:Customized Brand Name:oem Material:Steel, Steel, Steel C45 <\/p>","protected":false},"author":1,"featured_media":516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14005,658,14007,14004,14006,14008],"class_list":["post-4073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-gjj-m5-gear-rack-in-colombia","tag-lg60-m8-gear-rack","tag-m1-m2-m3-m4-m5-m6-cnc-gear-rack-in-phoenix","tag-m8-construction-hoist-gear-rack-in-australia","tag-steel-gear-rack-in-kota","tag-wire-rope-in-sri-lanka"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts\/4073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/comments?post=4073"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts\/4073\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/media\/516"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/media?parent=4073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/categories?post=4073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/tags?post=4073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}