{"id":1844,"date":"2017-05-19T10:56:28","date_gmt":"2017-05-19T10:56:28","guid":{"rendered":"https:\/\/www.ketabkhun.com\/gear\/steel-casting-rack-and-pinion-gears.html"},"modified":"2017-05-19T10:56:28","modified_gmt":"2017-05-19T10:56:28","slug":"steel-casting-rack-and-pinion-gears","status":"publish","type":"post","link":"https:\/\/www.ketabkhun.com\/gear\/es\/steel-casting-rack-and-pinion-gears.html","title":{"rendered":"steel casting rack and pinion gears"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale166.jpg\" alt=\"steel casting rack and pinion gears\" \/><br \/>\nImage of steel casting rack and pinion gears<\/p>\n<h3 class=\"alpha-title\">Detalles r\u00e1pidos: <\/h3>\n<ul class=\"alpha-ali\">\n<li>Forma: Engranaje de cremallera<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Model Number:M1-M10, OEM rack pinion<\/li>\n<li>Marca: GJJ, BAODA<\/li>\n<li>Material: acero, acero C45, G60, S45, S43<\/li>\n<li>Procesamiento:Fundici\u00f3n a presi\u00f3n<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar:No est\u00e1ndar<\/li>\n<li>color: negro<\/li>\n<li>Grade:standard grade<\/li>\n<li>Tratamiento superficial: pulido\/pintura\/recubrimiento en polvo<\/li>\n<li>Usage:rack pinion helical modules1-10<\/li>\n<li>\u00c1ngulo de presi\u00f3n: 20 o seg\u00fan dibujos<\/li>\n<li>Certificaci\u00f3n: ISO, CE, SGS<\/li>\n<li>rack Modules:Modules1-Modules10<\/li>\n<li>N\u00famero de teech: 15<\/li>\n<\/ul>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">V\u00eddeo relacionado: <\/h3>\n<p><iframe loading=\"lazy\" src=\"https:\/\/drive.google.com\/file\/d\/0B_Qz2h1-Y02pcGw3VC0tcUdKUVk\/preview\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Descripci\u00f3n: <\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale297.jpg\" alt=\"steel casting rack and pinion gears\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale43.jpg\" alt=\"steel casting rack and pinion gears\" \/><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale229.jpg\" alt=\"steel casting rack and pinion gears\" \/><\/p>\n<div style=\"clear:both\"><\/div>\n<h3 class=\"alpha-title\">Dejar un mensaje: <\/h3>\n<div class=\"alpha-contact\"><\/script><\/div>\n<div style=\"clear:both\"><\/div>\n<div class=\"alpha-like\">\n<h3 class=\"alpha-title\">Tambi\u00e9n te puede interesar:<\/h3>\n<ul class=\"alpha\">\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale269.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Reducer 16: 1reduction Gearbox with Gjj Baoda<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>\u00c9xito N.\u00ba: 16: 1 12: 1<\/li>\n<li>Dureza: Superficie del diente endurecida<\/li>\n<li>Disposici\u00f3n: Coaxial<\/li>\n<li>Step: Single-Step<\/li>\n<li>N\u00famero de \u00e9xito: 16: 1, 12: 1, 10: 1<\/li>\n<li>Potencia: Caja de engranajes de ascensor de 11 kW, 15 kW, 18 kW<\/li>\n<li>Par de salida: 800\/960 nm<\/li>\n<li>Velocidad de entrada: 1500\/min<\/li>\n<li>Elevaci\u00f3n de peso: Caja de engranajes de ascensor de 2 t o m\u00e1s<\/li>\n<li>De: \u00c9xito<\/li>\n<li>Especificaci\u00f3n: alrededor de 7-15 d\u00edas despu\u00e9s de recibir el pago.<\/li>\n<li>C\u00f3digo HS: 84313900<\/li>\n<li>Aplicaci\u00f3n: Motor, coches el\u00e9ctricos, motocicletas, maquinaria, marina, juguetes, maquinaria agr\u00edcola, coche<\/li>\n<li>Instalaci\u00f3n: 90 grados<\/li>\n<li>Gear Shape: Conical &#8211; Cylindrical Gear<\/li>\n<li>Tipo: Reductor de engranajes planetarios<\/li>\n<li>Potencia nominal: 11,02\/11,06 kW<\/li>\n<li>Caja de cambios: 1:16<\/li>\n<li>Uso: Caja de engranajes del ascensor<\/li>\n<li>Etiqueta privada: Caja de engranajes de ascensor disponible<\/li>\n<li>Fuente: Electric<\/li>\n<li>Paquete de transporte: Caja de madera<\/li>\n<li>Origen: Shangh\u00e1i<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Mod 2 Spur Gear in Adana, Custom Gear Rack<\/div>\n<div class=\"alpha-text1\">Export to: Adana, Haiphong, Jodhpur etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale275.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">Competitive price driven systerm electric motor for construction Hoist \/ building lift \/ material elevator<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: SC200\/200, SC150\/150, SCA200\/200<\/li>\n<li>Capacidad de carga nominal (kg): 1000 kg-2000 kg<\/li>\n<li>Velocidad de elevaci\u00f3n: 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 250 m<\/li>\n<li>Dimensiones (largo x ancho x alto): 3,0 x 1,3 (1,5) x 2,2<\/li>\n<li>Peso del cargador: 2000 kg<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Tipo: Equipo de elevaci\u00f3n para edificios de construcci\u00f3n SC200\/200<\/li>\n<li>Voltaje-frecuencia: 380-50 HZ (se puede organizar seg\u00fan los requisitos del cliente)<\/li>\n<li>Velocidad de elevaci\u00f3n: 33 m\/min, 0-33 m\/min, 0-55 m\/min<\/li>\n<li>Capacidad nominal: 1000 kg \u2013 2000 kg<\/li>\n<li>Potencia del motor: 11 kW*2, 11 kW*3, 15 kW*2, 12 kW*2, 13 kW*2<\/li>\n<li>Certificaci\u00f3n: ISO9000, CE, GOST, est\u00e1ndar de Corea<\/li>\n<li>Secci\u00f3n del m\u00e1stil: 650 x 650 x 1508 (mm) Peso: 145 kg<\/li>\n<li>Tipo de accionamiento: engranaje y cremallera<\/li>\n<li>Tratamiento de superficie: Granallado, acabado horneado, galvanizado, pintura.<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Mod1 Rack in Haiphong, Construction Hoist Rack in Jodhpur<\/div>\n<div class=\"alpha-text1\">Export to: Peru, Tajikistan etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale220.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">CE ISO GOST approved sc series passenger hoist, construction building platform<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Condici\u00f3n:Nuevo<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Marca:Success<\/li>\n<li>N\u00famero de modelo: SC200\/200<\/li>\n<li>Uso: Polipasto de construcci\u00f3n<\/li>\n<li>Fuente de energ\u00eda: el\u00e9ctrica<\/li>\n<li>Tipo de eslinga: cable<\/li>\n<li>Maximum Lifting Weight:2000kg*2<\/li>\n<li>Altura m\u00e1xima de elevaci\u00f3n: 150 m<\/li>\n<li>Velocidad de elevaci\u00f3n: 33 m\/min<\/li>\n<li>Certificaci\u00f3n: ISO9000, CE, GOST, Est\u00e1ndar de Corea, ISO9000, CE, GOST, Est\u00e1ndar de Corea<\/li>\n<li>Garant\u00eda: 1 a\u00f1o<\/li>\n<li>Servicio posventa proporcionado: Ingenieros disponibles para dar servicio a maquinaria en el extranjero.<\/li>\n<li>Type:construction building platform<\/li>\n<li>Cage:Double cage<\/li>\n<li>Rated capacity:2000kg per cage (2000kg*2)<\/li>\n<li>Motor Power:3*11kw per cage (3*11kw*2)<\/li>\n<li>Lifting speed:33m\/min<\/li>\n<li>Voltaje-frecuencia: 380-50 HZ (se puede organizar seg\u00fan los requisitos del cliente)<\/li>\n<li>Secci\u00f3n del m\u00e1stil: 650 x 650 x 1508 (mm) Peso: 145 kg<\/li>\n<li>Tipo de accionamiento: engranaje y cremallera<\/li>\n<li>Tratamiento de superficie: Granallado, acabado horneado, galvanizado, pintura.<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: C45 Bevel Pinion Gears in Peru, Gear Pinion Gear Box in Tajikistan<\/div>\n<div class=\"alpha-text1\">Export to: Islamabad, Antwerp, La Plata, Adana etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale385.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">spare parts of Construction Hoist and construction,rack and pinion gears<\/h3>\n<div class=\"alpha-text2\">\n<ul>\n<li>Shape:Bevel<\/li>\n<li>Tooth Profile:Herringbone Gear<\/li>\n<li>Direction:Right Hand<\/li>\n<li>Material:Stainless Steel, Steel<\/li>\n<li>Procesamiento: Fundici\u00f3n de precisi\u00f3n<\/li>\n<li>Pressure Angle:gear<\/li>\n<li>Lugar de origen: Shangh\u00e1i, China (Continental)<\/li>\n<li>Model Number:bevel gear M3<\/li>\n<li>Marca:Success<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar:Est\u00e1ndar<\/li>\n<li>Certificate:BV, ISO9001-2000<\/li>\n<li>Steel Type:Alloy Steel planetary gear<\/li>\n<li>Surface Treatment:Grinding<\/li>\n<li>Process:Forging &amp; Casting planetary gear<\/li>\n<li>Chemical Control:Spectrograph<\/li>\n<li>Weight:MAX 55T<\/li>\n<li>Gear Accuracy:MAX Grade 6<\/li>\n<li>Defect Control: UT, MT<\/li>\n<li>Inspection:planetary gear<\/li>\n<\/ul>\n<\/div>\n<div class=\"alpha-text1\">Keywords: Custom Gear Rack, Gear Pinion Gear Box in Tajikistan<\/div>\n<div class=\"alpha-text1\">Export to: Lahore, United States, La Plata, Islamabad etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<li>\n<div class=\"alpha-img\"><img decoding=\"async\" width=\"200\" src=\"https:\/\/www.ketabkhun.com\/gear\/wp-content\/uploads\/Cheap_Gear_Rack_For_Construction_Hoist_Sale91.jpg\"><\/div>\n<div class=\"alpha-text\">\n<h3 class=\"alpha-title\">GJJ, BAODA Construction Hoist Spare Parts<\/h3>\n<div class=\"alpha-text2\">\n<ul class=\"basic-info-list\">\n<li>Success NO.: baoda, gjj<\/li>\n<li>Aplicaci\u00f3n: Polipasto de construcci\u00f3n<\/li>\n<li>Condici\u00f3n: Nuevo<\/li>\n<li>Processing: Die Casting, Hobbing<\/li>\n<li>Certificado de Calidad: ISO9000:2008<\/li>\n<li>Engranaje: 15 dientes<\/li>\n<li>Paquete de transporte: Caja de madera<\/li>\n<li>Origen: Shangh\u00e1i, China<\/li>\n<li>Tipo: Engranaje de cremallera<\/li>\n<li>Certificaci\u00f3n: CE, ISO9001:2000, SGS<\/li>\n<li>Material: Steel, Steel,C45,G60<\/li>\n<li>Est\u00e1ndar o no est\u00e1ndar: Est\u00e1ndar<\/li>\n<li>Dientes helicoidales: tambi\u00e9n disponibles<\/li>\n<li>De: \u00c9xito<\/li>\n<li>Specification: CE, SGS<\/li>\n<li>C\u00f3digo HS: 84313900<\/li>\n<\/ul><\/div>\n<div class=\"alpha-text1\">Keywords: Mod 2 Spur Gear in Adana, C45 Bevel Pinion Gears in Peru<\/div>\n<div class=\"alpha-text1\">Export to: Adana, Jodhpur, Tajikistan, Antwerp etc.<\/div>\n<div class=\"alpha-contact\">\n<div id=\"MyLiveChatContainer\"><\/div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.ketabkhun.com\/contactus\/\">Dejar un mensaje<\/a><\/div>\n<\/div>\n<\/li>\n<\/ul>\n<\/div>\n<div style=\"clear:both\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Image of steel casting rack and pinion gears Quick Details: Shape:Rack Gear Place of Origin:Shanghai, China (Mainland) Model Number:M1-M10, OEM rack pinion Brand Name:GJJ ,BAODA <\/p>","protected":false},"author":1,"featured_media":46,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5214,5213,695,5215,5211,5212],"class_list":["post-1844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gear-rack","tag-c45-bevel-pinion-gears-in-peru","tag-construction-hoist-rack-in-jodhpur","tag-custom-gear-rack","tag-gear-pinion-gear-box-in-tajikistan","tag-mod-2-spur-gear-in-adana","tag-mod1-rack-in-haiphong"],"_links":{"self":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts\/1844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/comments?post=1844"}],"version-history":[{"count":0,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/posts\/1844\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/media?parent=1844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/categories?post=1844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ketabkhun.com\/gear\/es\/wp-json\/wp\/v2\/tags?post=1844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}